{"id":1007,"date":"2026-01-27T00:36:25","date_gmt":"2026-01-26T17:36:25","guid":{"rendered":"https:\/\/bns.vn\/tu-van-tham-tra-thiet-ke\/"},"modified":"2026-04-02T15:28:39","modified_gmt":"2026-04-02T08:28:39","slug":"%e8%ae%be%e8%ae%a1%e5%92%a8%e8%af%a2%e4%b8%8e%e5%ae%a1%e6%9f%a5","status":"publish","type":"page","link":"https:\/\/bnsvn943.mbws.vn\/zh-hans\/%e8%ae%be%e8%ae%a1%e5%92%a8%e8%af%a2%e4%b8%8e%e5%ae%a1%e6%9f%a5\/","title":{"rendered":"\u8bbe\u8ba1\u54a8\u8be2\u4e0e\u5ba1\u67e5"},"content":{"rendered":"\n\t<section class=\"section dark\" id=\"section_761876796\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"821\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/image-pagehead.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-595984526\">\n\n\t<div id=\"col-2130485685\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <div id=\"page-header-969004804\" class=\"page-header-wrapper\">\n  <div class=\"page-title dark simple-title\">\n\n    \n    <div class=\"page-title-inner container align-top flex-row medium-flex-wrap\" >\n              <div class=\"title-wrapper is-xlarge flex-col text-left medium-text-center\">\n          <h1 class=\"entry-title mb-0\">\n            \u8bbe\u8ba1\u54a8\u8be2\u4e0e\u5ba1\u67e5          <\/h1>\n        <\/div>\n                    <div class=\"title-content flex-col flex-right text-right medium-text-center\">\n              <\/div>\n    <\/div>\n\n       <\/div>\n    <\/div>\n  \n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-595984526 > .col > .col-inner {\n  padding: 0px 55px 0px 55px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_761876796 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 620px;\n}\n#section_761876796 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#section_761876796 .section-bg img {\n  object-position: 43% 54%;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section responsive\" id=\"section_445206159\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-922740591\">\n\n\t<div id=\"col-1391732055\" class=\"col medium-12 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2131414926\" class=\"text\">\n\t\t\n<h2>\u8bbe\u8ba1\u54a8\u8be2\u4e0e\u5ba1\u67e5<\/h2>\n\t\t\n<style>\n#text-2131414926 {\n  font-size: 1.4rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1899837788\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: justify;\">BNS \u63d0\u4f9b\u4e13\u4e1a\u7684\u8bbe\u8ba1\u54a8\u8be2\u548c\u8bbe\u8ba1\u5ba1\u67e5\u670d\u52a1\uff0c\u786e\u4fdd\u6240\u6709\u6280\u672f\u56fe\u7eb8\u5177\u6709\u9ad8\u5ea6\u51c6\u786e\u6027\u3001\u4f18\u5316\u6027\uff0c\u5e76\u5b8c\u5168\u7b26\u5408\u76f8\u5173\u6cd5\u5f8b\u6cd5\u89c4\u8981\u6c42\u3002\u6211\u4eec\u7684\u670d\u52a1\u8303\u56f4\u5305\u62ec\u7ed3\u6784\u8bbe\u8ba1\u3001\u53ef\u884c\u6027\u8bc4\u4f30\u3001\u8bbe\u8ba1\u6587\u4ef6\u5ba1\u67e5\uff0c\u4ee5\u53ca\u4e3a\u5de5\u4e1a\u4e0e\u6c11\u7528\u9879\u76ee\u63d0\u51fa\u6280\u672f\u6539\u8fdb\u65b9\u6848\u3002<\/p>\n<p style=\"text-align: justify;\">\u6211\u4eec\u7684\u5de5\u7a0b\u5e08\u56e2\u961f\u91c7\u7528\u5148\u8fdb\u7684\u8bbe\u8ba1\u8f6f\u4ef6\uff0c\u5e76\u9075\u5faa\u56fd\u9645\u6807\u51c6\uff0c\u81f4\u529b\u4e8e\u63d0\u4f9b\u5b89\u5168\u3001\u9ad8\u6548\u4e14\u5177\u6210\u672c\u4f18\u52bf\u7684\u6280\u672f\u89e3\u51b3\u65b9\u6848\u3002\u4f8b\u5982\uff0c\u5728 H\u00f2a Ph\u00e1t H\u1ea3i D\u01b0\u01a1ng \u94a2\u94c1\u751f\u4ea7\u7efc\u5408\u4f53\u9879\u76ee \u4e2d\uff0c\u6211\u4eec\u8d1f\u8d23\u5ba1\u67e5\u4e0e\u8bbe\u8ba1\u591a\u4e2a\u5173\u952e\u9879\u76ee\uff0c\u5305\u62ec\u9664\u5c18\u7cfb\u7edf\u57fa\u7840\u548c\u673a\u7535\u5382\u623f\uff0c\u786e\u4fdd\u5176\u8010\u4e45\u6027\u4e0e\u8fd0\u884c\u6548\u7387\u3002<\/p>\n<p style=\"text-align: justify;\">BNS \u7684\u670d\u52a1\u6709\u52a9\u4e8e\u964d\u4f4e\u6280\u672f\u98ce\u9669\u3001\u4f18\u5316\u65bd\u5de5\u6210\u672c\u5e76\u63d0\u5347\u5de5\u7a0b\u6574\u4f53\u8d28\u91cf\u3002\u51ed\u501f\u8de8\u9886\u57df\u7684\u4e13\u4e1a\u7ecf\u9a8c\u4e0e\u5353\u8d8a\u7684\u4e13\u4e1a\u7cbe\u795e\uff0c\u6211\u4eec\u627f\u8bfa\u4e3a\u5ba2\u6237\u63d0\u4f9b\u53ef\u9760\u7684\u8bbe\u8ba1\u65b9\u6848\uff0c\u52a9\u529b\u6210\u529f\u5b9e\u65bd\u5404\u7c7b\u590d\u6742\u9879\u76ee<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-541240934\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1941267363\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:56.25%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"786\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1941267363 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_445206159 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n\t<section class=\"section responsive dark\" id=\"section_205836636\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/1-2.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle\"  id=\"row-410425921\">\n\n\t<div id=\"col-839861262\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_205836636 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 660px;\n}\n#section_205836636 .section-bg img {\n  object-position: 43% 71%;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n\n\t<section class=\"section responsive\" id=\"section_491319709\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1048420429\">\n\n\t<div id=\"col-485346729\" class=\"col medium-12 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1395526372\" class=\"text\">\n\t\t\n<h2>\u8a2d\u8a08\u8aee\u8a62\u53ca\u8a2d\u8a08\u9a57\u8b49\u9805\u76ee<\/h2>\n\t\t\n<style>\n#text-1395526372 {\n  font-size: 1.4rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1274179317\" class=\"col medium-12 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"accordion\">\n\t<div id=\"accordion-3018041657\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3018041657-label\" class=\"accordion-title plain active\" href=\"#accordion-item-\u8d85\u7ec6\u78b3\u9178\u9499\u7c89\u4f53\u751f\u4ea7\u52a0\u5de5\u5382\u9879\u76ee\" aria-expanded=\"true\" aria-controls=\"accordion-3018041657-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"\u5207\u6362\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>\u8d85\u7ec6\u78b3\u9178\u9499\u7c89\u4f53\u751f\u4ea7\u52a0\u5de5\u5382\u9879\u76ee<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3018041657-content\" class=\"accordion-inner\" style=\"display: block;\" aria-labelledby=\"accordion-3018041657-label\" >\n\t\t\t\n<p style=\"text-align: justify;\"><strong>\u9879\u76ee\u5730\u5740<\/strong><br \/>\u4e49\u5b89\u7701\uff0c\u4e49\u575b\u53bf\uff0c\u4e49\u4f1a\u4e61\uff0c\u4e49\u575b\u5de5\u4e1a\u533a<\/p>\n<p style=\"text-align: justify;\"><strong>\u4e1a\u4e3b\u540d\u79f0<\/strong><br \/>\u5fb7\u76db\u65b0\u6750\u6599\u6280\u672f\u6709\u9650\u8d23\u4efb\u516c\u53f8<\/p>\n<p style=\"text-align: justify;\"><strong>\u627f\u5305\u540d\u79f0<\/strong><br \/>\u9879\u76ee\u7ba1\u7406\u54a8\u8be2<\/p>\n<p style=\"text-align: justify;\"><strong>\u5ba1\u67e5\u54a8\u8be2<\/strong><br \/>\u65bd\u5de5\u5efa\u8bbe\u76d1\u7406\u54a8\u8be2<\/p>\n<p style=\"text-align: justify;\"><strong>\u5408\u540c\u65f6\u95f4<\/strong><br \/>2024\u5e74 \u2013 2025\u5e74<\/p>\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns- slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/01.-ANH-CHINH-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/01.-ANH-CHINH-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/02-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/02-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/03-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/03-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/04-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/04-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/05-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/05-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/06-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/06-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/07-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/07-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/08-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/08-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/09-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/09-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/10-1-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/10-1-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/11-1-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/11-1-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"894,895,896,897,898,899,900,901,902,903,904\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1342564882\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1342564882-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u548c\u53d1\u6cb3\u5357\u5bb6\u7535\u5236\u51b7\u5de5\u5382\u9879\u76ee\" aria-expanded=\"false\" aria-controls=\"accordion-1342564882-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"\u5207\u6362\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>\u548c\u53d1\u6cb3\u5357\u5bb6\u7535\u5236\u51b7\u5de5\u5382\u9879\u76ee<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1342564882-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1342564882-label\" >\n\t\t\t\n<p style=\"text-align: justify;\"><strong>\u9879\u76ee\u5730\u5740<\/strong><br \/>\u6cb3\u5357\u7701\uff0c\u7ef4\u4ed9\u53bf\uff0c\u548c\u9ea6\u5de5\u4e1a\u533a<\/p>\n<p style=\"text-align: justify;\"><strong>\u4e1a\u4e3b\u540d\u79f0<\/strong><br \/>\u548c\u53d1\u6cb3\u5357\u5bb6\u7535\u80a1\u4efd\u516c\u53f8<\/p>\n<p style=\"text-align: justify;\"><strong>\u627f\u5305\u540d\u79f0<\/strong><br \/>\u76d1\u7406\u54a8\u8be2\u53ca\u5ba1\u67e5\u54a8\u8be2<\/p>\n<p style=\"text-align: justify;\"><strong>\u5408\u540c\u65f6\u95f4<\/strong><br \/>2021\u5e74<\/p>\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns- slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/01.-ANH-CHINH-1-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/01.-ANH-CHINH-1-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_1-vp-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_1-vp-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_4-kho-tp-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_4-kho-tp-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_6-nm-sx-nhua-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_6-nm-sx-nhua-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_7-8-nm-sx-co-khi-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_7-8-nm-sx-co-khi-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_9-nha-an-ca-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_9-nha-an-ca-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_21-Photo-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_21-Photo-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_23-Photo-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_23-Photo-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_24-Photo-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_24-Photo-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_TT3-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2022-1-4_TT3-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/nha-an2022-4-19_26-Photo-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/nha-an2022-4-19_26-Photo-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"926,927,928,929,930,931,932,933,934,935,936\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3266477818\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3266477818-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u51b7\u51bb\u67dc\u751f\u4ea7\u5382\u9879\u76ee\" aria-expanded=\"false\" aria-controls=\"accordion-3266477818-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"\u5207\u6362\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>\u51b7\u51bb\u67dc\u751f\u4ea7\u5382\u9879\u76ee<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3266477818-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3266477818-label\" >\n\t\t\t\n<p style=\"text-align: justify;\"><strong>\u9879\u76ee\u5730\u5740<\/strong><br \/>\u5df4\u5730\u5934\u987f\u7701\uff0c\u5bcc\u7f8e\u5e02\u9547\uff0c\u65b0\u798f\u574a\uff0c\u5bcc\u7f8e2\u53f7\u6269\u5c55\u5de5\u4e1a\u533a<\/p>\n<p style=\"text-align: justify;\"><strong>\u4e1a\u4e3b\u540d\u79f0<\/strong><br \/>\u548c\u53d1\u5bcc\u7f8e\u5236\u51b7\u80a1\u4efd\u516c\u53f8<\/p>\n<p style=\"text-align: justify;\"><strong>\u627f\u5305\u540d\u79f0<\/strong><br \/>\u76d1\u7406\u54a8\u8be2\u53ca\u5ba1\u67e5\u54a8\u8be2<\/p>\n<p style=\"text-align: justify;\"><strong>\u5408\u540c\u65f6\u95f4<\/strong><br \/>2021\u5e74<\/p>\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns- slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/1-13.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1513\" height=\"810\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/1-13.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"952,953,954\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2-15-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2-15-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"952,953,954\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/3-12.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1474\" height=\"967\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/3-12.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"952,953,954\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1877386817\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1877386817-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u548c\u53d1-\u6995\u6a58\u94a2\u94c1\u751f\u4ea7\u8054\u5408\u533a\u9879\u76ee\" aria-expanded=\"false\" aria-controls=\"accordion-1877386817-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"\u5207\u6362\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>\u548c\u53d1-\u6995\u6a58\u94a2\u94c1\u751f\u4ea7\u8054\u5408\u533a\u9879\u76ee<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1877386817-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1877386817-label\" >\n\t\t\t\n<p style=\"text-align: justify;\"><strong>\u9879\u76ee\u5730\u5740<\/strong><br \/>\u5e7f\u4e49\u7701\uff0c\u5e73\u5c71\u53bf\uff0c\u5e73\u4e1c\u4e61<\/p>\n<p style=\"text-align: justify;\"><strong>\u4e1a\u4e3b\u540d\u79f0<\/strong><br \/>\u548c\u53d1-\u6995\u6a58\u94a2\u94c1\u80a1\u4efd\u516c\u53f8<\/p>\n<p><strong>\u627f\u5305\u540d\u79f0<\/strong><\/p>\n<ul>\n<li>\u8bbe\u8ba1\u54a8\u8be2<\/li>\n<li>\u5ba1\u67e5\u54a8\u8be2<\/li>\n<li>\u65bd\u5de5\u5efa\u8bbe\u76d1\u7406\u54a8\u8be2<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>\u5408\u540c\u65f6\u95f4<\/strong><br \/>2024\u5e74 \u2013 2025\u5e74<\/p>\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns- slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/01.-ANH-CHINH-2-3-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1600\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/01.-ANH-CHINH-2-3-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/47-nha-may-thep-hoa-phat-dung-quat.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/47-nha-may-thep-hoa-phat-dung-quat.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/123.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/123.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hoa-phat-dung-quat-2-1.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hoa-phat-dung-quat-2-1.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hoa-phat-dung-quat-1.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hoa-phat-dung-quat-1.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-1.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-1.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-2.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-2.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-3.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-3.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-4.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"721\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-4.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-5.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"721\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-5.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/khu-lh-hoa-phat-5.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1276\" height=\"956\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/khu-lh-hoa-phat-5.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-6.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"721\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/hpdq2-6.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/Profile-BNS-03.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2123\" height=\"1005\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/Profile-BNS-03.jpeg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/z5176549503129-13bbf4b8d010794d98498ab3460422f6.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1438\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/z5176549503129-13bbf4b8d010794d98498ab3460422f6.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/02-1-1-scaled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1187\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/02-1-1-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1857,939,940,942,941,943,944,945,946,947,949,948,950,951,1851\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3590660952\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3590660952-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u540c\u9a91\u91d1\u65b9\u516c\u5bd3\" aria-expanded=\"false\" aria-controls=\"accordion-3590660952-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"\u5207\u6362\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>\u540c\u9a91\u91d1\u65b9\u516c\u5bd3<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3590660952-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3590660952-label\" >\n\t\t\t\n<p style=\"text-align: justify;\"><strong>\u9879\u76ee\u5730\u5740<\/strong><br \/>\u5317\u5b81\u7701\uff0c\u6148\u5c71\u5e02\uff0c\u5e84\u4e0b\u574a<\/p>\n<p style=\"text-align: justify;\"><strong>\u4e1a\u4e3b\u540d\u79f0<\/strong><br \/>\u901a\u534f\u6709\u9650\u516c\u53f8<\/p>\n<p style=\"text-align: justify;\"><strong>\u627f\u5305\u5185\u5bb9\uff1a<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">\u9879\u76ee\u7ba1\u7406\u54a8\u8be2<\/li>\n<li style=\"text-align: justify;\">\u76d1\u7406\u54a8\u8be2<\/li>\n<li style=\"text-align: justify;\">\u5ba1\u67e5\u54a8\u8be2<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>\u5408\u540c\u65f6\u95f4<\/strong><br \/>2018\u5e74<\/p>\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns- slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/3-13.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1090\" height=\"763\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/3-13.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"962,963,961\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/1-15.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1610\" height=\"1169\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/1-15.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"962,963,961\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2-17.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"786\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/2-17.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"962,963,961\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3952837167\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3952837167-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u5b81\u534f\u4e61\u89c4\u5212\u5efa\u8bbe\u5de5\u7a0b\u6295\u8d44\u9879\u76ee\" aria-expanded=\"false\" aria-controls=\"accordion-3952837167-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"\u5207\u6362\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>\u5b81\u534f\u4e61\u89c4\u5212\u5efa\u8bbe\u5de5\u7a0b\u6295\u8d44\u9879\u76ee<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3952837167-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3952837167-label\" >\n\t\t\t\n<p style=\"text-align: justify;\"><strong>\u9879\u76ee\u5730\u5740<\/strong><br \/>\u6cb3\u5185\u5e02\uff0c\u5609\u6797\u53bf\uff0c\u5b81\u534f\u4e61<\/p>\n<p style=\"text-align: justify;\"><strong>\u4e1a\u4e3b\u540d\u79f0<\/strong><br \/>\u4fca\u5bb9\u8d38\u6613\u96c6\u56e2\u6709\u9650\u8d23\u4efb\u516c\u53f8<\/p>\n<p style=\"text-align: justify;\"><strong>\u627f\u5305\u540d\u79f0<\/strong><br \/>\u7ed3\u6784\u8ba1\u7b97\u4e0e\u8bbe\u8ba1\u6587\u4ef6\u56fe\u7eb8\u4fee\u6b63<\/p>\n<p style=\"text-align: justify;\"><strong>\u5408\u540c\u65f6\u95f4<\/strong><br \/>2017\u5e74<\/p>\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns- slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/construction-investment-1-scaled.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1765\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/construction-investment-1-scaled.png\" class=\"attachment-original size-original\" alt=\"\" ids=\"1909,1907,1911\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/construction-investment-2.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1125\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/construction-investment-2.png\" class=\"attachment-original size-original\" alt=\"\" ids=\"1909,1907,1911\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/construction-investment-3.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/construction-investment-3.jpg\" class=\"attachment-original size-original\" alt=\"\" ids=\"1909,1907,1911\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-913572624\" class=\"accordion-item\">\n\t\t<a id=\"accordion-913572624-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u5efa\u7b51\u6750\u6599\u53ca\u6c34\u6ce5\u6dfb\u52a0\u5242\u751f\u4ea7\u5382\u9879\u76ee\" aria-expanded=\"false\" aria-controls=\"accordion-913572624-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"\u5207\u6362\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>\u5efa\u7b51\u6750\u6599\u53ca\u6c34\u6ce5\u6dfb\u52a0\u5242\u751f\u4ea7\u5382\u9879\u76ee<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-913572624-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-913572624-label\" >\n\t\t\t\n<p style=\"text-align: justify;\"><strong>\u9879\u76ee\u5730\u5740<\/strong><br \/>\u6cb3\u9759\u7701\uff0c\u5947\u82f1\u5e02\u9547\uff0c\u5947\u5229\u4e61<\/p>\n<p style=\"text-align: justify;\"><strong>\u4e1a\u4e3b\u540d\u79f0<\/strong><br \/>\u8d8a\u6d77\u7c89\u7164\u7070\u5904\u7406\u4e0e\u56de\u6536\u6709\u9650\u516c\u53f8<\/p>\n<p style=\"text-align: justify;\"><strong>\u627f\u5305\u540d\u79f0<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">\u9879\u76ee\u7b56\u5212<\/li>\n<li style=\"text-align: justify;\">\u521d\u6b65\u8bbe\u8ba1<\/li>\n<li style=\"text-align: justify;\">\u65bd\u5de5\u56fe\u8bbe\u8ba1<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>\u5408\u540c\u65f6\u95f4<br \/><\/strong>2019\u5e74<\/p>\n\n  \n    <div class=\"row large-columns-1 medium-columns- small-columns- slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/cement-additives.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1256\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/cement-additives.png\" class=\"attachment-original size-original\" alt=\"\" ids=\"1915\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"1\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3817380278\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3817380278-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u56fd\u5185\u9500\u552e\u4e0e\u51fa\u53e3\u6728\u4ea7\u54c1\u52a0\u5de5\u751f\u4ea7\u5de5\u5382\" aria-expanded=\"false\" aria-controls=\"accordion-3817380278-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"\u5207\u6362\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>\u56fd\u5185\u9500\u552e\u4e0e\u51fa\u53e3\u6728\u4ea7\u54c1\u52a0\u5de5\u751f\u4ea7\u5de5\u5382<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3817380278-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3817380278-label\" >\n\t\t\t\n<p style=\"text-align: justify;\"><strong>\u9879\u76ee\u5730\u5740<\/strong><br \/>\u6cb3\u9759\u7701\uff0c\u5947\u82f1\u5e02\u9547<\/p>\n<p style=\"text-align: justify;\"><strong>\u4e1a\u4e3b\u540d\u79f0<\/strong><br \/>\u5b89\u8d8a\u53d1\u80fd\u6e90\u4e00\u4eba\u6709\u9650\u8d23\u4efb\u516c\u53f8\uff08\u6cb3\u9759\uff09<\/p>\n<p style=\"text-align: justify;\"><strong>\u627f\u5305\u540d\u79f0<\/strong><br \/>1\/500\u89c4\u5212\u7f16\u5236<\/p>\n<p style=\"text-align: justify;\"><strong>\u5408\u540c\u65f6\u95f4<\/strong><br \/>2019\u5e74<\/p>\n\n  \n    <div class=\"row large-columns-1 medium-columns- small-columns- slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/forest-production-scaled.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1856\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/forest-production-scaled.png\" class=\"attachment-original size-original\" alt=\"\" ids=\"1919\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"1\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2474088845\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2474088845-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u5305\u88c5\u751f\u4ea7\u5de5\u5382\u9879\u76ee\" aria-expanded=\"false\" aria-controls=\"accordion-2474088845-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"\u5207\u6362\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>\u5305\u88c5\u751f\u4ea7\u5de5\u5382\u9879\u76ee<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2474088845-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2474088845-label\" >\n\t\t\t\n<p style=\"text-align: justify;\"><strong>\u9879\u76ee\u5730\u5740<\/strong><br \/>\u6cb3\u9759\u7701\uff0c\u5947\u82f1\u5e02\u9547\uff0c\u5947\u5229\u4e61<\/p>\n<p style=\"text-align: justify;\"><strong>\u4e1a\u4e3b\u540d\u79f0<\/strong><br \/>\u7eff\u6c5f\u5305\u88c5\u80a1\u4efd\u516c\u53f8<\/p>\n<p style=\"text-align: justify;\"><strong>\u627f\u5305\u540d\u79f0<\/strong><br \/>1\/500\u89c4\u5212\u7f16\u5236 + \u5730\u8d28\u52d8\u5bdf + \u5730\u5f62\u6d4b\u91cf + \u521d\u6b65\u8bbe\u8ba1 + \u65bd\u5de5\u56fe\u8bbe\u8ba1<\/p>\n<p style=\"text-align: justify;\"><strong>\u5408\u540c\u65f6\u95f4<\/strong><br \/>2018\u5e74<\/p>\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns- slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/packaging-factory-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/packaging-factory-1.png\" class=\"attachment-original size-original\" alt=\"\" ids=\"1921,1923\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/packaging-factory-2.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/bnsvn943.mbws.vn\/wp-content\/uploads\/packaging-factory-2.png\" class=\"attachment-original size-original\" alt=\"\" ids=\"1921,1923\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" columns=\"2\" slider_nav_style=\"simple\" slider_nav_position=\"outside\" image_height=\"56.25%\" image_size=\"original\" image_hover=\"zoom\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_491319709 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header-light.php","meta":{"footnotes":""},"class_list":["post-1007","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bnsvn943.mbws.vn\/zh-hans\/wp-json\/wp\/v2\/pages\/1007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bnsvn943.mbws.vn\/zh-hans\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bnsvn943.mbws.vn\/zh-hans\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bnsvn943.mbws.vn\/zh-hans\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bnsvn943.mbws.vn\/zh-hans\/wp-json\/wp\/v2\/comments?post=1007"}],"version-history":[{"count":33,"href":"https:\/\/bnsvn943.mbws.vn\/zh-hans\/wp-json\/wp\/v2\/pages\/1007\/revisions"}],"predecessor-version":[{"id":2041,"href":"https:\/\/bnsvn943.mbws.vn\/zh-hans\/wp-json\/wp\/v2\/pages\/1007\/revisions\/2041"}],"wp:attachment":[{"href":"https:\/\/bnsvn943.mbws.vn\/zh-hans\/wp-json\/wp\/v2\/media?parent=1007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}